{"id":549,"date":"2017-02-05T20:19:08","date_gmt":"2017-02-05T23:19:08","guid":{"rendered":"http:\/\/deportesalternativos.com\/argentina\/?p=549"},"modified":"2017-02-05T20:19:08","modified_gmt":"2017-02-05T23:19:08","slug":"el-dvd-2017-ya-esta-a-la-venta","status":"publish","type":"post","link":"https:\/\/deportesalternativos.com\/argentina\/el-dvd-2017-ya-esta-a-la-venta\/","title":{"rendered":"El DVD 2017 ya est\u00e1 a la venta"},"content":{"rendered":"<p><a href=\"https:\/\/deportesalternativos.com\/argentina\/wp-content\/uploads\/2017\/02\/tapaindex2017.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-547\" src=\"https:\/\/deportesalternativos.com\/argentina\/wp-content\/uploads\/2017\/02\/tapaindex2017-300x270.jpg\" alt=\"tapaindex2017\" width=\"300\" height=\"270\" srcset=\"https:\/\/deportesalternativos.com\/argentina\/wp-content\/uploads\/2017\/02\/tapaindex2017-300x270.jpg 300w, https:\/\/deportesalternativos.com\/argentina\/wp-content\/uploads\/2017\/02\/tapaindex2017.jpg 497w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Ya comenz\u00f3 la pre-venta del DVD Index Alternativo 2017. En plena producci\u00f3n videogr\u00e1fica, hablamos con Ricardo Acu\u00f1a, quien est\u00e1 a cargo de la direcci\u00f3n y el armado: \u00abSer\u00e1 una edici\u00f3n exclusiva\u00bb anticip\u00f3 y adem\u00e1s agreg\u00f3 \u00abcontendr\u00e1 300 videos: 150 los estoy armando en donde cuento a modo general cada uno de los deportes que contiene el DVD. Los otros 150 son videos seleccionados donde se ver\u00e1 la acci\u00f3n de cada uno de ellos\u00bb. La comercializaci\u00f3n comenz\u00f3 el 4\/2\/17 y el precio promocional (AR$250 \u00f3 US$16) se mantendr\u00e1 hasta el d\u00eda 14\/3. El d\u00eda 15\/03\/2017 ser\u00e1 el d\u00eda del lanxamiento y comenzar\u00e1 la distribuci\u00f3n a los compradores en la pre-venta. Luego, a partir del mismo 15\/3\/2017 el precio ser\u00e1 de AR$350.<\/p>\n<p>Un material \u00fanico para los fan\u00e1ticos de los Alternativos. Y en un a\u00f1o que ver\u00e1 tambien el nacimiento de la Tienda Alternativa, lugar donde comprar material deportivo alternativo y mucho de fabricaci\u00f3n nacional. Asimismo, el trabajo bibliogr\u00e1fico no descansa y tambi\u00e9n ser\u00e1 el a\u00f1o del primer libro de Juegos y Deportes Alternativos. Mantengan el contacto y larga vida a los Alternativ@s!<\/p>\n<p>Valeria Pugliese (Prensa CADALT)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya comenz\u00f3 la pre-venta del DVD Index Alternativo 2017. En plena producci\u00f3n videogr\u00e1fica, hablamos con Ricardo Acu\u00f1a, quien est\u00e1 a cargo de la direcci\u00f3n y el armado: \u00abSer\u00e1 una edici\u00f3n exclusiva\u00bb anticip\u00f3 y adem\u00e1s agreg\u00f3 \u00abcontendr\u00e1 300 videos: 150 los estoy armando en donde cuento a modo general cada uno de los deportes que contiene&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/deportesalternativos.com\/argentina\/el-dvd-2017-ya-esta-a-la-venta\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":""},"categories":[17,5,12,7,6,4,1,15,9,3],"tags":[],"_links":{"self":[{"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/posts\/549"}],"collection":[{"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/comments?post=549"}],"version-history":[{"count":1,"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/posts\/549\/revisions"}],"predecessor-version":[{"id":550,"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/posts\/549\/revisions\/550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/media\/547"}],"wp:attachment":[{"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/media?parent=549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/categories?post=549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deportesalternativos.com\/argentina\/wp-json\/wp\/v2\/tags?post=549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}